{"id":636,"count":0,"description":"","link":"https:\/\/mangoanimate.com\/blog\/vi\/category\/text-animation\/article-to-video\/","name":"b\u00e0i vi\u1ebft cho video","slug":"article-to-video","taxonomy":"category","parent":660,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Article to Video - Mango Animate<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mangoanimate.com\/blog\/vi\/wp-json\/wp\/v2\/categories\/636\" \/>\n<meta property=\"og:locale\" content=\"vi_VN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Article to Video - Mango Animate\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mangoanimate.com\/blog\/vi\/category\/text-animation\/article-to-video\/\" \/>\n<meta property=\"og:site_name\" content=\"Mango Animate\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/category\/text-animation\/article-to-video\/\",\"url\":\"https:\/\/mangoanimate.com\/blog\/category\/text-animation\/article-to-video\/\",\"name\":\"Article to Video - Mango Animate\",\"isPartOf\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/category\/text-animation\/article-to-video\/#breadcrumb\"},\"inLanguage\":\"vi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/category\/text-animation\/article-to-video\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mangoanimate.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Text Animation\",\"item\":\"https:\/\/mangoanimate.com\/blog\/category\/text-animation\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Article to Video\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/#website\",\"url\":\"https:\/\/mangoanimate.com\/blog\/\",\"name\":\"Mango Animate\",\"description\":\"Animated Businesss Video Tips, Ideas and More\",\"publisher\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mangoanimate.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"vi\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/#organization\",\"name\":\"Mango Animate\",\"url\":\"https:\/\/mangoanimate.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"vi\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp\",\"contentUrl\":\"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp\",\"width\":240,\"height\":32,\"caption\":\"Mango Animate\"},\"image\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MangoAnimate\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Article to Video - Mango Animate","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mangoanimate.com\/blog\/vi\/wp-json\/wp\/v2\/categories\/636","og_locale":"vi_VN","og_type":"article","og_title":"Article to Video - Mango Animate","og_url":"https:\/\/mangoanimate.com\/blog\/vi\/category\/text-animation\/article-to-video\/","og_site_name":"Mango Animate","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mangoanimate.com\/blog\/category\/text-animation\/article-to-video\/","url":"https:\/\/mangoanimate.com\/blog\/category\/text-animation\/article-to-video\/","name":"Article to Video - Mango Animate","isPartOf":{"@id":"https:\/\/mangoanimate.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/mangoanimate.com\/blog\/category\/text-animation\/article-to-video\/#breadcrumb"},"inLanguage":"vi"},{"@type":"BreadcrumbList","@id":"https:\/\/mangoanimate.com\/blog\/category\/text-animation\/article-to-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mangoanimate.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Text Animation","item":"https:\/\/mangoanimate.com\/blog\/category\/text-animation\/"},{"@type":"ListItem","position":3,"name":"Article to Video"}]},{"@type":"WebSite","@id":"https:\/\/mangoanimate.com\/blog\/#website","url":"https:\/\/mangoanimate.com\/blog\/","name":"Mango Animate","description":"Animated Businesss Video Tips, Ideas and More","publisher":{"@id":"https:\/\/mangoanimate.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mangoanimate.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"vi"},{"@type":"Organization","@id":"https:\/\/mangoanimate.com\/blog\/#organization","name":"Mango Animate","url":"https:\/\/mangoanimate.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"vi","@id":"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp","contentUrl":"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp","width":240,"height":32,"caption":"Mango Animate"},"image":{"@id":"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MangoAnimate\/"]}]}},"_links":{"self":[{"href":"https:\/\/mangoanimate.com\/blog\/vi\/wp-json\/wp\/v2\/categories\/636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mangoanimate.com\/blog\/vi\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mangoanimate.com\/blog\/vi\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/mangoanimate.com\/blog\/vi\/wp-json\/wp\/v2\/categories\/660"}],"wp:post_type":[{"href":"https:\/\/mangoanimate.com\/blog\/vi\/wp-json\/wp\/v2\/posts?categories=636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}