{"id":508,"count":1,"description":"Create your exclusive animated infographics in 10 minutes.","link":"https:\/\/mangoanimate.com\/blog\/he\/category\/infographic-video\/animated-infographics\/","name":"\u05d0\u05d9\u05e0\u05e4\u05d5\u05d2\u05e8\u05e4\u05d9\u05e7\u05d4 \u05de\u05d5\u05e0\u05e4\u05e9\u05ea","slug":"animated-infographics","taxonomy":"category","parent":502,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Animated Infographics - Mango Animate<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mangoanimate.com\/blog\/he\/wp-json\/wp\/v2\/categories\/508\" \/>\n<meta property=\"og:locale\" content=\"he_IL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Animated Infographics - Mango Animate\" \/>\n<meta property=\"og:description\" content=\"Create your exclusive animated infographics in 10 minutes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mangoanimate.com\/blog\/he\/category\/infographic-video\/animated-infographics\/\" \/>\n<meta property=\"og:site_name\" content=\"Mango Animate\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/animated-infographics\/\",\"url\":\"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/animated-infographics\/\",\"name\":\"Animated Infographics - Mango Animate\",\"isPartOf\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/animated-infographics\/#breadcrumb\"},\"inLanguage\":\"he-IL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/animated-infographics\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mangoanimate.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Infographic Video\",\"item\":\"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Animated Infographics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/#website\",\"url\":\"https:\/\/mangoanimate.com\/blog\/\",\"name\":\"Mango Animate\",\"description\":\"Animated Businesss Video Tips, Ideas and More\",\"publisher\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mangoanimate.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"he-IL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/#organization\",\"name\":\"Mango Animate\",\"url\":\"https:\/\/mangoanimate.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"he-IL\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp\",\"contentUrl\":\"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp\",\"width\":240,\"height\":32,\"caption\":\"Mango Animate\"},\"image\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MangoAnimate\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Animated Infographics - Mango Animate","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mangoanimate.com\/blog\/he\/wp-json\/wp\/v2\/categories\/508","og_locale":"he_IL","og_type":"article","og_title":"Animated Infographics - Mango Animate","og_description":"Create your exclusive animated infographics in 10 minutes.","og_url":"https:\/\/mangoanimate.com\/blog\/he\/category\/infographic-video\/animated-infographics\/","og_site_name":"Mango Animate","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/animated-infographics\/","url":"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/animated-infographics\/","name":"Animated Infographics - Mango Animate","isPartOf":{"@id":"https:\/\/mangoanimate.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/animated-infographics\/#breadcrumb"},"inLanguage":"he-IL"},{"@type":"BreadcrumbList","@id":"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/animated-infographics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mangoanimate.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Infographic Video","item":"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/"},{"@type":"ListItem","position":3,"name":"Animated Infographics"}]},{"@type":"WebSite","@id":"https:\/\/mangoanimate.com\/blog\/#website","url":"https:\/\/mangoanimate.com\/blog\/","name":"Mango Animate","description":"Animated Businesss Video Tips, Ideas and More","publisher":{"@id":"https:\/\/mangoanimate.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mangoanimate.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"he-IL"},{"@type":"Organization","@id":"https:\/\/mangoanimate.com\/blog\/#organization","name":"Mango Animate","url":"https:\/\/mangoanimate.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"he-IL","@id":"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp","contentUrl":"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp","width":240,"height":32,"caption":"Mango Animate"},"image":{"@id":"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MangoAnimate\/"]}]}},"_links":{"self":[{"href":"https:\/\/mangoanimate.com\/blog\/he\/wp-json\/wp\/v2\/categories\/508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mangoanimate.com\/blog\/he\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mangoanimate.com\/blog\/he\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/mangoanimate.com\/blog\/he\/wp-json\/wp\/v2\/categories\/502"}],"wp:post_type":[{"href":"https:\/\/mangoanimate.com\/blog\/he\/wp-json\/wp\/v2\/posts?categories=508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}