{"id":1131,"count":5,"description":"","link":"https:\/\/mangoanimate.com\/blog\/fr\/category\/ai-earth-zoom-in\/","name":"Zoom sur la Terre par IA","slug":"ai-earth-zoom-in","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AI Earth Zoom In - Mango Animate<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mangoanimate.com\/blog\/fr\/wp-json\/wp\/v2\/categories\/1131\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AI Earth Zoom In - Mango Animate\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mangoanimate.com\/blog\/fr\/category\/ai-earth-zoom-in\/\" \/>\n<meta property=\"og:site_name\" content=\"Mango Animate\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/category\/ai-earth-zoom-in\/\",\"url\":\"https:\/\/mangoanimate.com\/blog\/category\/ai-earth-zoom-in\/\",\"name\":\"AI Earth Zoom In - Mango Animate\",\"isPartOf\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/category\/ai-earth-zoom-in\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/category\/ai-earth-zoom-in\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mangoanimate.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AI Earth Zoom In\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/#website\",\"url\":\"https:\/\/mangoanimate.com\/blog\/\",\"name\":\"Mango Animate\",\"description\":\"Animated Businesss Video Tips, Ideas and More\",\"publisher\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mangoanimate.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/#organization\",\"name\":\"Mango Animate\",\"url\":\"https:\/\/mangoanimate.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp\",\"contentUrl\":\"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp\",\"width\":240,\"height\":32,\"caption\":\"Mango Animate\"},\"image\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MangoAnimate\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AI Earth Zoom In - Mango Animate","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mangoanimate.com\/blog\/fr\/wp-json\/wp\/v2\/categories\/1131","og_locale":"fr_FR","og_type":"article","og_title":"AI Earth Zoom In - Mango Animate","og_url":"https:\/\/mangoanimate.com\/blog\/fr\/category\/ai-earth-zoom-in\/","og_site_name":"Mango Animate","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mangoanimate.com\/blog\/category\/ai-earth-zoom-in\/","url":"https:\/\/mangoanimate.com\/blog\/category\/ai-earth-zoom-in\/","name":"AI Earth Zoom In - Mango Animate","isPartOf":{"@id":"https:\/\/mangoanimate.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/mangoanimate.com\/blog\/category\/ai-earth-zoom-in\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/mangoanimate.com\/blog\/category\/ai-earth-zoom-in\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mangoanimate.com\/blog\/"},{"@type":"ListItem","position":2,"name":"AI Earth Zoom In"}]},{"@type":"WebSite","@id":"https:\/\/mangoanimate.com\/blog\/#website","url":"https:\/\/mangoanimate.com\/blog\/","name":"Mango Animate","description":"Animated Businesss Video Tips, Ideas and More","publisher":{"@id":"https:\/\/mangoanimate.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mangoanimate.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mangoanimate.com\/blog\/#organization","name":"Mango Animate","url":"https:\/\/mangoanimate.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp","contentUrl":"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp","width":240,"height":32,"caption":"Mango Animate"},"image":{"@id":"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MangoAnimate\/"]}]}},"_links":{"self":[{"href":"https:\/\/mangoanimate.com\/blog\/fr\/wp-json\/wp\/v2\/categories\/1131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mangoanimate.com\/blog\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mangoanimate.com\/blog\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/mangoanimate.com\/blog\/fr\/wp-json\/wp\/v2\/posts?categories=1131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}