{"id":502,"count":2,"description":"Create your specific animated infographic videos in 10 minutes.","link":"https:\/\/mangoanimate.com\/blog\/da\/category\/infographic-video\/","name":"Infografisk video","slug":"infographic-video","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Infographic Video - Mango Animate<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mangoanimate.com\/blog\/da\/wp-json\/wp\/v2\/categories\/502\" \/>\n<meta property=\"og:locale\" content=\"da_DK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infographic Video - Mango Animate\" \/>\n<meta property=\"og:description\" content=\"Create your specific animated infographic videos in 10 minutes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mangoanimate.com\/blog\/da\/category\/infographic-video\/\" \/>\n<meta property=\"og:site_name\" content=\"Mango Animate\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/\",\"url\":\"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/\",\"name\":\"Infographic Video - Mango Animate\",\"isPartOf\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/#breadcrumb\"},\"inLanguage\":\"da-DK\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mangoanimate.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Infographic Video\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/#website\",\"url\":\"https:\/\/mangoanimate.com\/blog\/\",\"name\":\"Mango Animate\",\"description\":\"Animated Businesss Video Tips, Ideas and More\",\"publisher\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mangoanimate.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"da-DK\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/#organization\",\"name\":\"Mango Animate\",\"url\":\"https:\/\/mangoanimate.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp\",\"contentUrl\":\"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp\",\"width\":240,\"height\":32,\"caption\":\"Mango Animate\"},\"image\":{\"@id\":\"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/MangoAnimate\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Infographic Video - Mango Animate","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mangoanimate.com\/blog\/da\/wp-json\/wp\/v2\/categories\/502","og_locale":"da_DK","og_type":"article","og_title":"Infographic Video - Mango Animate","og_description":"Create your specific animated infographic videos in 10 minutes.","og_url":"https:\/\/mangoanimate.com\/blog\/da\/category\/infographic-video\/","og_site_name":"Mango Animate","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/","url":"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/","name":"Infographic Video - Mango Animate","isPartOf":{"@id":"https:\/\/mangoanimate.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/#breadcrumb"},"inLanguage":"da-DK"},{"@type":"BreadcrumbList","@id":"https:\/\/mangoanimate.com\/blog\/category\/infographic-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mangoanimate.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Infographic Video"}]},{"@type":"WebSite","@id":"https:\/\/mangoanimate.com\/blog\/#website","url":"https:\/\/mangoanimate.com\/blog\/","name":"Mango Animate","description":"Animated Businesss Video Tips, Ideas and More","publisher":{"@id":"https:\/\/mangoanimate.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mangoanimate.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"da-DK"},{"@type":"Organization","@id":"https:\/\/mangoanimate.com\/blog\/#organization","name":"Mango Animate","url":"https:\/\/mangoanimate.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp","contentUrl":"https:\/\/mangoanimate.com\/blog\/wp-content\/uploads\/2024\/10\/Mango_Animate_logo_.webp","width":240,"height":32,"caption":"Mango Animate"},"image":{"@id":"https:\/\/mangoanimate.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MangoAnimate\/"]}]}},"_links":{"self":[{"href":"https:\/\/mangoanimate.com\/blog\/da\/wp-json\/wp\/v2\/categories\/502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mangoanimate.com\/blog\/da\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mangoanimate.com\/blog\/da\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/mangoanimate.com\/blog\/da\/wp-json\/wp\/v2\/posts?categories=502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}